{"id":41560,"date":"2022-03-14T10:02:39","date_gmt":"2022-03-14T10:02:39","guid":{"rendered":"https:\/\/www.headshop.nl\/?post_type=product&#038;p=41560"},"modified":"2024-09-17T11:01:27","modified_gmt":"2024-09-17T11:01:27","slug":"blueberry-flavored-papers","status":"publish","type":"product","link":"https:\/\/www.headshop.nl\/pt\/blueberry-flavored-papers\/","title":{"rendered":"Amora Flavored Papers"},"content":{"rendered":"<h2>Rolling Papers da Juicy Jay<\/h2>\n<p>Juicy Jay's ou simplesmente Juicy \u00e9 uma daquelas marcas de papel de enrolar que ou se ama ou se odeia. A sua cole\u00e7\u00e3o de papel de enrolar \u00e9 \u00fanica devido ao facto de todos os pap\u00e9is Juicy virem com um sabor e um design colorido. Qualquer sabor que possas imaginar, eles t\u00eam-no!<\/p>\n<p>Isto faz com que enrolar charros com papel aromatizado seja uma atividade excitante, porque o papel que escolheres afectar\u00e1 o sabor e o cheiro do teu charro. Escolha o seu sabor preferido e fume os seus charros com estilo!<\/p>","protected":false},"excerpt":{"rendered":"<p>Se gostas do sabor a mirtilo fresco, vais adorar estes pap\u00e9is! Os pap\u00e9is com sabor a mirtilo da Juicy Jay's fazem com que qualquer charro tenha um sabor e um cheiro fant\u00e1sticos. Pega num papel, enrola o teu charro e sente o rico sabor a mirtilo em cada tragada que d\u00e1s. Ah, e at\u00e9 fazem o teu charro parecer mais fixe. T\u00e3o saboroso!<\/p>","protected":false},"featured_media":45528,"template":"","meta":[],"product_brand":[],"product_cat":[297,793,809,414,446,421,802],"product_tag":[],"class_list":{"0":"post-41560","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-all-products","7":"product_cat-color-papers","8":"product_cat-flavored-papers","9":"product_cat-headshop","10":"product_cat-papers","11":"product_cat-rolling-papers","12":"product_cat-slim-size","13":"product_shipping_class-creditcard-on","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-variable","21":"has-default-attributes"},"_links":{"self":[{"href":"https:\/\/www.headshop.nl\/pt\/wp-json\/wp\/v2\/product\/41560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.headshop.nl\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.headshop.nl\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.headshop.nl\/pt\/wp-json\/wp\/v2\/media\/45528"}],"wp:attachment":[{"href":"https:\/\/www.headshop.nl\/pt\/wp-json\/wp\/v2\/media?parent=41560"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.headshop.nl\/pt\/wp-json\/wp\/v2\/product_brand?post=41560"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.headshop.nl\/pt\/wp-json\/wp\/v2\/product_cat?post=41560"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.headshop.nl\/pt\/wp-json\/wp\/v2\/product_tag?post=41560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}